{"id":3632,"date":"2022-07-26T11:30:00","date_gmt":"2022-07-26T17:30:00","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=3632"},"modified":"2022-07-28T11:31:13","modified_gmt":"2022-07-28T17:31:13","slug":"capacitan-a-especialistas-informaticos-del-sistema-de-produccion-y-consumo","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2022\/07\/26\/capacitan-a-especialistas-informaticos-del-sistema-de-produccion-y-consumo\/","title":{"rendered":"Capacitan a especialistas inform\u00e1ticos del Sistema de Producci\u00f3n y Consumo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> El\u00a0<strong>Instituto Nicarag\u00fcense de Tecnolog\u00eda Agropecuaria ( INTA)<\/strong>, con el apoyo del\u00a0<strong>PMA<\/strong>\u00a0inici\u00f3 este martes la capacitaci\u00f3n de 20 especialistas en inform\u00e1tica de varias instituciones de gobierno que trabajan en el monitoreo satelital sobre las \u00e1reas de producci\u00f3n en\u00a0<strong>Nicaragua<\/strong>.  <a href=\"https:\/\/www.el19digital.com\/articulos\/ver\/titulo:130642-capacitan-a-especialistas-informaticos-del-sistema-de-produccion-y-consumo\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s... (opens in a new tab)\">Leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Instituto Nicarag\u00fcense de Tecnolog\u00eda Agropecuaria ( INTA), con el apoyo del\u00a0PMA\u00a0inici\u00f3 este martes la capacitaci\u00f3n de 20 especialistas en inform\u00e1tica<\/p>\n","protected":false},"author":1,"featured_media":3633,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-3632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/3632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=3632"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/3632\/revisions"}],"predecessor-version":[{"id":3634,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/3632\/revisions\/3634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/3633"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=3632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=3632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=3632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}