{"id":2878,"date":"2022-02-10T10:22:29","date_gmt":"2022-02-10T16:22:29","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=2878"},"modified":"2022-02-11T10:23:56","modified_gmt":"2022-02-11T16:23:56","slug":"inta-celebra-congreso-internacional-sobre-incremento-del-hato-ovino-y-caprino","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2022\/02\/10\/inta-celebra-congreso-internacional-sobre-incremento-del-hato-ovino-y-caprino\/","title":{"rendered":"INTA celebra Congreso Internacional sobre incremento del Hato Ovino y Caprino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>Instituto Nicarag\u00fcense de Tecnolog\u00eda Agropecuaria<\/strong>\u00a0(INTA) celebr\u00f3 este jueves el\u00a0<strong>Primer Congreso Internacional incremento del Hato Ovino y Caprino<\/strong>, utilizando t\u00e9cnicas del mejoramiento gen\u00e9tico.  <a href=\"https:\/\/www.el19digital.com\/articulos\/ver\/titulo:125231-inta-celebra-congreso-internacional-sobre-incremento-del-hato-ovino-y-caprino\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s (opens in a new tab)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nicarag\u00fcense de Tecnolog\u00eda Agropecuaria\u00a0(INTA) celebr\u00f3 este jueves el\u00a0Primer Congreso Internacional incremento del Hato Ovino y Caprino, utilizando t\u00e9cnicas<\/p>\n","protected":false},"author":1,"featured_media":2879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-2878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=2878"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2878\/revisions"}],"predecessor-version":[{"id":2880,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2878\/revisions\/2880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/2879"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=2878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=2878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=2878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}