{"id":2557,"date":"2022-01-08T10:32:13","date_gmt":"2022-01-08T16:32:13","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=2557"},"modified":"2022-01-10T10:34:13","modified_gmt":"2022-01-10T16:34:13","slug":"por-que-incrementaron-tanto-los-precios-de-los-insumos-agricolas-en-2021-aca-la-explicacion-del-sector","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2022\/01\/08\/por-que-incrementaron-tanto-los-precios-de-los-insumos-agricolas-en-2021-aca-la-explicacion-del-sector\/","title":{"rendered":"\u00bfPor qu\u00e9 incrementaron tanto los precios de los insumos agr\u00edcolas en 2021? Ac\u00e1 la explicaci\u00f3n del sector"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Seg\u00fan Anifoda, el principal proveedor de agroqu\u00edmicos de Nicaragua es China, seguido por Europa y Estados Unidos. Tambi\u00e9n la regi\u00f3n centroamericana e Israel son part\u00edcipes.  <a href=\"https:\/\/www.laprensa.com.ni\/2022\/01\/08\/economia\/2933652-por-que-incrementaron-tanto-los-precios-de-los-insumos-agricolas-en-2021-aca-la-explicacion-del-sector\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s (opens in a new tab)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan Anifoda, el principal proveedor de agroqu\u00edmicos de Nicaragua es China, seguido por Europa y Estados Unidos. Tambi\u00e9n la regi\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":2558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-2557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2557\/revisions"}],"predecessor-version":[{"id":2559,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2557\/revisions\/2559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=2557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}