{"id":2532,"date":"2021-12-13T11:14:26","date_gmt":"2021-12-13T17:14:26","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=2532"},"modified":"2021-12-13T11:15:55","modified_gmt":"2021-12-13T17:15:55","slug":"nuevas-variedades-de-cafe-en-nicaragua-en-busca-de-mejores-precios-conozca-su-parte-debil","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2021\/12\/13\/nuevas-variedades-de-cafe-en-nicaragua-en-busca-de-mejores-precios-conozca-su-parte-debil\/","title":{"rendered":"Nuevas variedades de caf\u00e9 en Nicaragua: en busca de mejores precios. Conozca su parte d\u00e9bil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Productores nicarag\u00fcenses introducen variedades de caf\u00e9 que garantizan la calidad que exigen los nichos de mercado que pagan mejores precios pero quedan expuestas a vulnerabilidades. <a href=\"https:\/\/www.laprensa.com.ni\/2021\/12\/13\/economia\/2923080-nuevas-variedades-de-cafe-en-nicaragua-en-busca-de-mejores-precios-conozca-su-parte-debil\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s (opens in a new tab)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Productores nicarag\u00fcenses introducen variedades de caf\u00e9 que garantizan la calidad que exigen los nichos de mercado que pagan mejores precios<\/p>\n","protected":false},"author":1,"featured_media":2533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-2532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=2532"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2532\/revisions"}],"predecessor-version":[{"id":2534,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2532\/revisions\/2534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/2533"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=2532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=2532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=2532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}