{"id":2062,"date":"2021-06-28T15:23:27","date_gmt":"2021-06-28T21:23:27","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=2062"},"modified":"2021-06-30T15:29:21","modified_gmt":"2021-06-30T21:29:21","slug":"crisis-economica-se-percibe-en-el-mercado-ventas-de-perecederos-estan-lentas","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2021\/06\/28\/crisis-economica-se-percibe-en-el-mercado-ventas-de-perecederos-estan-lentas\/","title":{"rendered":"Crisis econ\u00f3mica se percibe en el mercado; ventas de perecederos est\u00e1n lentas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Dos comerciantes del Mercado de Mayoreo relatan la poca demanda que enfrentan y las p\u00e9rdidas que amenazan sus negocios. <a href=\"https:\/\/www.laprensa.com.ni\/2021\/06\/28\/economia\/2843519-crisis-economica-se-percibe-en-el-mercado-ventas-de-perecederos-estan-lentas\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s (opens in a new tab)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos comerciantes del Mercado de Mayoreo relatan la poca demanda que enfrentan y las p\u00e9rdidas que amenazan sus negocios. Leer<\/p>\n","protected":false},"author":1,"featured_media":2063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-2062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=2062"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2062\/revisions"}],"predecessor-version":[{"id":2064,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/2062\/revisions\/2064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/2063"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=2062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=2062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=2062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}