{"id":1761,"date":"2021-05-06T11:08:53","date_gmt":"2021-05-06T17:08:53","guid":{"rendered":"https:\/\/cenida.una.edu.ni\/?p=1761"},"modified":"2021-05-07T11:11:43","modified_gmt":"2021-05-07T17:11:43","slug":"las-dudas-alrededor-de-la-planta-de-gas-natural-que-se-construye-en-puerto-sandino","status":"publish","type":"post","link":"https:\/\/cenida.una.edu.ni\/index.php\/2021\/05\/06\/las-dudas-alrededor-de-la-planta-de-gas-natural-que-se-construye-en-puerto-sandino\/","title":{"rendered":"Las dudas alrededor de la planta de gas natural que se construye en Puerto Sandino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Nicaragua celebra la instalaci\u00f3n de una planta de gas natural, pero hay algunos aspectos que las autoridades no aclaran en un proyecto de alto costo. <a href=\"https:\/\/www.laprensa.com.ni\/2021\/05\/06\/nacionales\/2819414-las-dudas-alrededor-de-la-planta-de-gas-natural-que-se-construye-en-puerto-sandino\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Leer m\u00e1s (opens in a new tab)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicaragua celebra la instalaci\u00f3n de una planta de gas natural, pero hay algunos aspectos que las autoridades no aclaran en<\/p>\n","protected":false},"author":1,"featured_media":1762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-1761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-agropecuarias"],"_links":{"self":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/1761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/comments?post=1761"}],"version-history":[{"count":1,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/1761\/revisions"}],"predecessor-version":[{"id":1763,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/posts\/1761\/revisions\/1763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media\/1762"}],"wp:attachment":[{"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/media?parent=1761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/categories?post=1761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cenida.una.edu.ni\/index.php\/wp-json\/wp\/v2\/tags?post=1761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}